{"id":63,"count":2,"description":"","link":"https:\/\/www.mobilist.com.tr\/en\/category\/ios-development\/","name":"iOS Development","slug":"ios-development","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>iOS Development Archives - Mobilist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iOS Development Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilist\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mobilist_labs\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/\",\"url\":\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/\",\"name\":\"iOS Development Archives - Mobilist\",\"isPartOf\":{\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mobilist.com.tr\/tr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iOS Development\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#website\",\"url\":\"https:\/\/www.mobilist.com.tr\/en\/\",\"name\":\"Mobilist\",\"description\":\"Dijitalin Kusursuz Hali\",\"publisher\":{\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mobilist.com.tr\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#organization\",\"name\":\"Mobilist\",\"url\":\"https:\/\/www.mobilist.com.tr\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mobilist.com.tr\/wp-content\/uploads\/2024\/03\/web-logo-text-only-2.png\",\"contentUrl\":\"https:\/\/www.mobilist.com.tr\/wp-content\/uploads\/2024\/03\/web-logo-text-only-2.png\",\"width\":400,\"height\":78,\"caption\":\"Mobilist\"},\"image\":{\"@id\":\"https:\/\/www.mobilist.com.tr\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mobilistlabs\",\"https:\/\/x.com\/mobilist_labs\",\"https:\/\/www.instagram.com\/mobilist\/\",\"https:\/\/www.linkedin.com\/company\/2498352\/admin\/feed\/posts\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"iOS Development Archives - Mobilist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/","og_locale":"en_US","og_type":"article","og_title":"iOS Development Archives","og_url":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/","og_site_name":"Mobilist","twitter_card":"summary_large_image","twitter_site":"@mobilist_labs","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/","url":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/","name":"iOS Development Archives - Mobilist","isPartOf":{"@id":"https:\/\/www.mobilist.com.tr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/3.67.17.170:443\/tr\/category\/ios-development\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mobilist.com.tr\/tr\/"},{"@type":"ListItem","position":2,"name":"iOS Development"}]},{"@type":"WebSite","@id":"https:\/\/www.mobilist.com.tr\/en\/#website","url":"https:\/\/www.mobilist.com.tr\/en\/","name":"Mobilist","description":"Dijitalin Kusursuz Hali","publisher":{"@id":"https:\/\/www.mobilist.com.tr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mobilist.com.tr\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mobilist.com.tr\/en\/#organization","name":"Mobilist","url":"https:\/\/www.mobilist.com.tr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mobilist.com.tr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mobilist.com.tr\/wp-content\/uploads\/2024\/03\/web-logo-text-only-2.png","contentUrl":"https:\/\/www.mobilist.com.tr\/wp-content\/uploads\/2024\/03\/web-logo-text-only-2.png","width":400,"height":78,"caption":"Mobilist"},"image":{"@id":"https:\/\/www.mobilist.com.tr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mobilistlabs","https:\/\/x.com\/mobilist_labs","https:\/\/www.instagram.com\/mobilist\/","https:\/\/www.linkedin.com\/company\/2498352\/admin\/feed\/posts\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.mobilist.com.tr\/en\/wp-json\/wp\/v2\/categories\/63"}],"collection":[{"href":"https:\/\/www.mobilist.com.tr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.mobilist.com.tr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.mobilist.com.tr\/en\/wp-json\/wp\/v2\/posts?categories=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}